{"id":2739,"date":"2010-03-22T15:38:48","date_gmt":"2010-03-22T20:38:48","guid":{"rendered":"http:\/\/www.icesi.edu.co\/editorial\/?p=2739"},"modified":"2025-08-12T17:12:02","modified_gmt":"2025-08-12T22:12:02","slug":"easyreg","status":"publish","type":"post","link":"https:\/\/www.icesi.edu.co\/editorial\/easyreg\/","title":{"rendered":"EasyReg"},"content":{"rendered":"<div class=\"ead-preview\"><div class=\"ead-document\" style=\"position: relative;\"><div class=\"ead-iframe-wrapper\"><iframe src=\"\/\/docs.google.com\/viewer?url=https%3A%2F%2Frepository.icesi.edu.co%2Fbitstreams%2F1bd3051f-899e-425c-9ef8-12f454f8ea4c%2Fdownload&amp;embedded=true&amp;hl=en\" title=\"Embedded Document\" class=\"ead-iframe\" style=\"width: 0px;height: 0px;border: none;visibility: hidden;\"><\/iframe><\/div>\t\t\t<div class=\"ead-document-loading\" style=\"width:100%;height:100%;position:absolute;left:0;top:0;z-index:10;\">\n\t\t\t\t<div class=\"ead-loading-wrap\">\n\t\t\t\t\t<div class=\"ead-loading-main\">\n\t\t\t\t\t\t<div class=\"ead-loading\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.icesi.edu.co\/editorial\/wp-content\/plugins\/embed-any-document\/images\/loading.svg\" width=\"55\" height=\"55\" alt=\"Loader\">\n\t\t\t\t\t\t\t<span>Loading...<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"ead-loading-foot\">\n\t\t\t\t\t\t<div class=\"ead-loading-foot-title\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.icesi.edu.co\/editorial\/wp-content\/plugins\/embed-any-document\/images\/EAD-logo.svg\" alt=\"EAD Logo\" width=\"36\" height=\"23\"\/>\n\t\t\t\t\t\t\t<span>Taking too long?<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<p>\n\t\t\t\t\t\t\t<div class=\"ead-document-btn ead-reload-btn\" role=\"button\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.icesi.edu.co\/editorial\/wp-content\/plugins\/embed-any-document\/images\/reload.svg\" alt=\"Reload\" width=\"12\" height=\"12\"\/> Reload document\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<span>|<\/span>\n\t\t\t\t\t\t\t<a href=\"https:\/\/docs.google.com\/viewer?url=https%3A%2F%2Frepository.icesi.edu.co%2Fbitstreams%2F1bd3051f-899e-425c-9ef8-12f454f8ea4c%2Fdownload&#038;hl=en\" class=\"ead-document-btn\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.icesi.edu.co\/editorial\/wp-content\/plugins\/embed-any-document\/images\/open.svg\" alt=\"Open\" width=\"12\" height=\"12\"\/> Open in new tab\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><p class=\"embed_download\"><a href=\"https:\/\/repository.icesi.edu.co\/bitstreams\/1bd3051f-899e-425c-9ef8-12f454f8ea4c\/download\" download target=\"_blank\" rel=\"noopener\">Download\/Descargar <\/a><\/p><\/div>\n<strong>T\u00edtulo completo:<\/strong> EasyReg: Aplicaciones para un curso de econometr\u00eda.<br \/>\n<strong>Autores:<\/strong> Julio C\u00e9sar Alonso y Paul Sema\u00e1n.<br \/>\n<strong>Editorial:<\/strong> Universidad Icesi.<br \/>\n<strong>A\u00f1o de edici\u00f3n:<\/strong> 2010.<br \/>\n<strong>ISBN:<\/strong> 978-958-8357-29-4.<br \/>\n<span id=\"post-ratings-2739\" class=\"post-ratings\" data-nonce=\"fab762655e\"><img decoding=\"async\" id=\"rating_2739_1\" src=\"https:\/\/www.icesi.edu.co\/editorial\/wp-content\/plugins\/wp-postratings\/images\/stars_crystal\/rating_on.gif\" alt=\"1 estrella\" title=\"1 estrella\" onmouseover=\"current_rating(2739, 1, '1 estrella');\" onmouseout=\"ratings_off(3, 0, 0);\" onclick=\"rate_post();\" onkeypress=\"rate_post();\" style=\"cursor: pointer; border: 0px;\" \/><img decoding=\"async\" id=\"rating_2739_2\" src=\"https:\/\/www.icesi.edu.co\/editorial\/wp-content\/plugins\/wp-postratings\/images\/stars_crystal\/rating_on.gif\" alt=\"2 estrellas\" title=\"2 estrellas\" onmouseover=\"current_rating(2739, 2, '2 estrellas');\" onmouseout=\"ratings_off(3, 0, 0);\" onclick=\"rate_post();\" onkeypress=\"rate_post();\" style=\"cursor: pointer; border: 0px;\" \/><img decoding=\"async\" id=\"rating_2739_3\" src=\"https:\/\/www.icesi.edu.co\/editorial\/wp-content\/plugins\/wp-postratings\/images\/stars_crystal\/rating_on.gif\" alt=\"3 estrellas\" title=\"3 estrellas\" onmouseover=\"current_rating(2739, 3, '3 estrellas');\" onmouseout=\"ratings_off(3, 0, 0);\" onclick=\"rate_post();\" onkeypress=\"rate_post();\" style=\"cursor: pointer; border: 0px;\" \/><img decoding=\"async\" id=\"rating_2739_4\" src=\"https:\/\/www.icesi.edu.co\/editorial\/wp-content\/plugins\/wp-postratings\/images\/stars_crystal\/rating_off.gif\" alt=\"4 estrellas\" title=\"4 estrellas\" onmouseover=\"current_rating(2739, 4, '4 estrellas');\" onmouseout=\"ratings_off(3, 0, 0);\" onclick=\"rate_post();\" onkeypress=\"rate_post();\" style=\"cursor: pointer; border: 0px;\" \/><img decoding=\"async\" id=\"rating_2739_5\" src=\"https:\/\/www.icesi.edu.co\/editorial\/wp-content\/plugins\/wp-postratings\/images\/stars_crystal\/rating_off.gif\" alt=\"5 estrellas\" title=\"5 estrellas\" onmouseover=\"current_rating(2739, 5, '5 estrellas');\" onmouseout=\"ratings_off(3, 0, 0);\" onclick=\"rate_post();\" onkeypress=\"rate_post();\" style=\"cursor: pointer; border: 0px;\" \/> (<strong>2<\/strong> votos, promedio: <strong>3,00<\/strong> sobre 5)<br \/><span class=\"post-ratings-text\" id=\"ratings_2739_text\"><\/span><\/span><span id=\"post-ratings-2739-loading\" class=\"post-ratings-loading\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.icesi.edu.co\/editorial\/wp-content\/plugins\/wp-postratings\/images\/loading.gif\" width=\"16\" height=\"16\" class=\"post-ratings-image\" \/>Loading...<\/span>\n&nbsp;<br \/>\n<div class=\"osc-res-tab tabbable   osc-tabs-left\"><div style=\"clear:both;width: 100%;\"><ul class=\"nav osc-res-nav nav-pills osc-tabs-left-ul\" id=\"oscitas-restabs-1-easyreg-67854\"><li class=\"active\"><a href=\"#ert_pane1-0\" data-toggle=\"tab\">Descripci\u00f3n<\/a><\/li><li class=\"\"><a href=\"#ert_pane1-1\" data-toggle=\"tab\">Contenido<\/a><\/li><li class=\"\"><a href=\"#ert_pane1-2\" data-toggle=\"tab\">Autor(es)<\/a><\/li><li class=\"\"><a href=\"#ert_pane1-3\" data-toggle=\"tab\">Catalogaci\u00f3n<\/a><\/li><\/ul><\/div><div style=\"clear:both;width: 100%;\"><ul class=\"tab-content\" id=\"oscitas-restabcontent-1-easyreg-67854\"><li class=\"tab-pane active\" id=\"ert_pane1-0\"><p style=\"text-align: justify;\">El an\u00e1lisis emp\u00edrico de la realidad a la luz de la teor\u00eda es cada d\u00eda m\u00e1s una parte fundamental en la formaci\u00f3n de un economista. La microeconom\u00eda, la macroeconom\u00eda y todo el andamiaje te\u00f3rico de los programas de pregrado son complementados con la econometr\u00eda para constituir la &#8220;caja de herramientas&#8221; de un economista. As\u00ed la econometr\u00eda no se puede entender como un fin, sino como un medio para encontrar las regularidades presentes en una realidad. Este libro pretende cumplir dos funciones. La primera es convertirse en un documento de consulta para economistas que desean emplear m\u00e9todos econom\u00e9tricos convencionales y una herramienta gratuita como <i>EasyReg<\/i>. La segunda funci\u00f3n es complementar un libro de texto convencional de econometr\u00eda brindando el puente entre la teor\u00eda econom\u00e9trica y la pr\u00e1ctica econom\u00e9trica mediante el uso del paquete econom\u00e9trico gratuito <i>EasyReg<\/i>. As\u00ed, este libro no pretende ser un sustituto de los manuales de econometr\u00eda actualmente disponibles en el mercado, sino un complemento a estos.<\/p>\n<p style=\"text-align: justify;\"><strong>C\u00f3mo citar (APA):<\/strong> Alonso, J.C. y Sema\u00e1n, P. (2010). <i>EasyReg: Aplicaciones para un curso de econometr\u00eda<\/i>. Cali: Universidad Icesi.<\/p><\/li><li class=\"tab-pane \" id=\"ert_pane1-1\"><strong>Tabla de contenido:<\/strong><\/p>\n<p><strong><u>I. El modelo de regresi\u00f3n m\u00faltiple<\/u><\/strong><\/p>\n<p>01 \/ Modelo de regresi\u00f3n m\u00faltiple<\/p>\n<p>02 \/ Inferencia y an\u00e1lisis de regresi\u00f3n<\/p>\n<p>03 \/ Variables dummy<\/p>\n<p><strong><u>II. Problemas econom\u00e9tricos<\/u><\/strong><\/p>\n<p>04 \/ Multicolinealidad<\/p>\n<p>05 \/ Heteroscedasticidad<\/p>\n<p>06 \/ Autocorrelaci\u00f3n<\/p>\n<p><strong><u>III. Otros modelos econom\u00e9tricos<\/u><\/strong><\/p>\n<p>07 \/ Modelos Logit y Probit<\/p>\n<p>08 \/ Ecuaciones simult\u00e1neas<\/p>\n<p><strong><u>IV. Respuestas<\/u><\/strong><br \/><\/li><li class=\"tab-pane \" id=\"ert_pane1-2\"><ul>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/orcid.org\/0000-0003-4890-7122\" target=\"_blank\" title=\"ORCID iD\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1012\" src=\"http:\/\/www.icesi.edu.co\/editorial\/wp-content\/uploads\/2020\/06\/ORCIDiD_icon16x16.png\" style=\"margin-right: 6px;\" alt=\"Icono ORCID\" width=\"16\" height=\"16\"><\/a><b>Julio C\u00e9sar Alonso<\/b>, Universidad Icesi (Cali, Colombia)<\/li>\n<li style=\"text-align: justify;\"><b>Paul Sema\u00e1n<\/b>, Universidad Icesi (Cali, Colombia)<\/li>\n<\/ul><\/li><li class=\"tab-pane \" id=\"ert_pane1-3\"><table>\n<tbody>\n<tr class=\"first odd\">\n<th width=\"160\">\n<p style=\"text-align: left;\">T\u00edtulo (ingl\u00e9s):<\/p>\n<\/th>\n<td class=\"data last\">EasyReg: Applications for an econometrics class.<\/td>\n<\/tr>\n<tr class=\"even\">\n<th>\n<p style=\"text-align: left;\">DOI\/URL:<\/p>\n<\/th>\n<td class=\"data last\"><a href=\"https:\/\/www.icesi.edu.co\/editorial\/easyreg\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.icesi.edu.co\/editorial\/easyreg\/<\/a><\/td>\n<\/tr>\n<tr class=\"odd\">\n<th>\n<p style=\"text-align: left;\">Editorial(es):<\/p>\n<\/th>\n<td class=\"data last\">Universidad Icesi.<\/td>\n<\/tr>\n<tr class=\"even\">\n<th>\n<p style=\"text-align: left;\">Autor(es):<\/p>\n<\/th>\n<td class=\"data last\">Julio C\u00e9sar Alonso y Paul Sema\u00e1n.<\/td>\n<\/tr>\n<tr class=\"odd\">\n<th>\n<p style=\"text-align: left;\">Palabras clave:<\/p>\n<\/th>\n<td class=\"data last\">Econometr\u00eda, EasyReg, Problemas econom\u00e9tricos.<\/td>\n<\/tr>\n<tr class=\"even\">\n<th>\n<p style=\"text-align: left;\">ISBN:<\/p>\n<\/th>\n<td class=\"data last\">978-958-8357-29-4.<\/td>\n<\/tr>\n<tr class=\"odd\">\n<th>\n<p style=\"text-align: left;\">Fecha de edici\u00f3n:<\/p>\n<\/th>\n<td class=\"data last\">Julio de 2010.<\/td>\n<\/tr>\n<tr class=\"even\">\n<th>\n<p style=\"text-align: left;\">No. de p\u00e1ginas:<\/p>\n<\/th>\n<td class=\"data last\">252.<\/td>\n<\/tr>\n<tr class=\"odd\">\n<th>\n<p style=\"text-align: left;\">Idioma(s):<\/p>\n<\/th>\n<td class=\"data last\">Espa\u00f1ol.<\/td>\n<\/tr>\n<tr class=\"even\">\n<th>\n<p style=\"text-align: left;\">Formato(s):<\/p>\n<\/th>\n<td class=\"data last\">Libro impreso (tapa r\u00fastica) y electr\u00f3nico (PDF).<\/td>\n<\/tr>\n<tr class=\"odd\">\n<th>\n<p style=\"text-align: left;\">Alto x ancho:<\/p>\n<\/th>\n<td class=\"data last\">29.3 x 21 cm<\/td>\n<\/tr>\n<tr class=\"even\">\n<th>\n<p style=\"text-align: left;\">Colecci\u00f3n:<\/p>\n<\/th>\n<td class=\"data last\">Edici\u00f3n especial.<\/td>\n<\/tr>\n<tr class=\"odd\">\n<th>\n<p style=\"text-align: left;\">Producto:<\/p>\n<\/th>\n<td class=\"data last\">Libro de texto.<\/td>\n<\/tr>\n<tr class=\"even\">\n<th>\n<p style=\"text-align: left;\">Observaciones:<\/p>\n<\/th>\n<td class=\"data last\">Incluye referencias bibliogr\u00e1ficas.<\/td>\n<\/tr>\n<tr class=\"last odd\">\n<th>\n<p style=\"text-align: left;\">Registro DSpace:<\/p>\n<\/th>\n<td class=\"data last\"><a href=\"https:\/\/hdl.handle.net\/10906\/130435\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1012\" src=\"http:\/\/www.icesi.edu.co\/editorial\/wp-content\/uploads\/2016\/04\/downloadIcon-e1460499009176.png\" alt=\"Icono de Repositorio - Contenido en la Nube\" width=\"25\" height=\"25\"><\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table><\/li><\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Keffiyeh authentic occupy ennui Carles street art. Beard VHS 8-bit, disrupt trust fund actually YOLO. Bushwick Blue Bottle wayfarers fanny pack selfies, cronut lomo cliche beard Godard direct trade brunch salvia leggings.<\/p>\n","protected":false},"author":3,"featured_media":8697,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[166],"tags":[265,325,328,353,415,416,418,442,450,451,452,732,1024],"class_list":["post-2739","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ediciones-especiales","tag-fcae","tag-libro-de-texto","tag-economia","tag-353","tag-contabilidad","tag-finanzas","tag-cienfi","tag-julio-cesar-alonso","tag-microeconomia","tag-macroeconomia","tag-econometria","tag-analytics","tag-metodos-cuantitativos"],"_links":{"self":[{"href":"https:\/\/www.icesi.edu.co\/editorial\/wp-json\/wp\/v2\/posts\/2739","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.icesi.edu.co\/editorial\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.icesi.edu.co\/editorial\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.icesi.edu.co\/editorial\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.icesi.edu.co\/editorial\/wp-json\/wp\/v2\/comments?post=2739"}],"version-history":[{"count":7,"href":"https:\/\/www.icesi.edu.co\/editorial\/wp-json\/wp\/v2\/posts\/2739\/revisions"}],"predecessor-version":[{"id":8711,"href":"https:\/\/www.icesi.edu.co\/editorial\/wp-json\/wp\/v2\/posts\/2739\/revisions\/8711"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.icesi.edu.co\/editorial\/wp-json\/wp\/v2\/media\/8697"}],"wp:attachment":[{"href":"https:\/\/www.icesi.edu.co\/editorial\/wp-json\/wp\/v2\/media?parent=2739"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.icesi.edu.co\/editorial\/wp-json\/wp\/v2\/categories?post=2739"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.icesi.edu.co\/editorial\/wp-json\/wp\/v2\/tags?post=2739"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}