{"id":6754,"date":"2022-10-17T18:03:00","date_gmt":"2022-10-17T23:03:00","guid":{"rendered":"https:\/\/www.icesi.edu.co\/editorial\/?p=6754"},"modified":"2025-04-23T17:01:04","modified_gmt":"2025-04-23T22:01:04","slug":"red-elite-cali","status":"publish","type":"post","link":"https:\/\/www.icesi.edu.co\/editorial\/red-elite-cali\/","title":{"rendered":"\u00c9lite, orden y conflicto"},"content":{"rendered":"<div class=\"ead-preview\"><div class=\"ead-document\" style=\"position: relative;\"><div class=\"ead-iframe-wrapper\"><iframe src=\"\/\/docs.google.com\/viewer?url=https%3A%2F%2Frepository.icesi.edu.co%2Fbitstreams%2Fa50b83bb-733d-4ed6-b1f1-8adc44094ad5%2Fdownload&amp;embedded=true&amp;hl=en\" title=\"Embedded Document\" class=\"ead-iframe\" style=\"width: 0px;height: 0px;border: none;visibility: hidden;\"><\/iframe><\/div>\t\t\t<div class=\"ead-document-loading\" style=\"width:100%;height:100%;position:absolute;left:0;top:0;z-index:10;\">\n\t\t\t\t<div class=\"ead-loading-wrap\">\n\t\t\t\t\t<div class=\"ead-loading-main\">\n\t\t\t\t\t\t<div class=\"ead-loading\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.icesi.edu.co\/editorial\/wp-content\/plugins\/embed-any-document\/images\/loading.svg\" width=\"55\" height=\"55\" alt=\"Loader\">\n\t\t\t\t\t\t\t<span>Loading...<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"ead-loading-foot\">\n\t\t\t\t\t\t<div class=\"ead-loading-foot-title\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.icesi.edu.co\/editorial\/wp-content\/plugins\/embed-any-document\/images\/EAD-logo.svg\" alt=\"EAD Logo\" width=\"36\" height=\"23\"\/>\n\t\t\t\t\t\t\t<span>Taking too long?<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<p>\n\t\t\t\t\t\t\t<div class=\"ead-document-btn ead-reload-btn\" role=\"button\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.icesi.edu.co\/editorial\/wp-content\/plugins\/embed-any-document\/images\/reload.svg\" alt=\"Reload\" width=\"12\" height=\"12\"\/> Reload document\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<span>|<\/span>\n\t\t\t\t\t\t\t<a href=\"https:\/\/docs.google.com\/viewer?url=https%3A%2F%2Frepository.icesi.edu.co%2Fbitstreams%2Fa50b83bb-733d-4ed6-b1f1-8adc44094ad5%2Fdownload&#038;hl=en\" class=\"ead-document-btn\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.icesi.edu.co\/editorial\/wp-content\/plugins\/embed-any-document\/images\/open.svg\" alt=\"Open\" width=\"12\" height=\"12\"\/> Open in new tab\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><p class=\"embed_download\"><a href=\"https:\/\/repository.icesi.edu.co\/bitstreams\/a50b83bb-733d-4ed6-b1f1-8adc44094ad5\/download\" download target=\"_blank\" rel=\"noopener\">Download\/Descargar <\/a><\/p><\/div>\n<strong>T\u00edtulo completo:<\/strong> \u00c9lite, orden y conflicto. Sobre c\u00f3mo se construy\u00f3 un orden social en Cali 1910-1953.<br \/>\n<strong>Colecci\u00f3n:<\/strong> Exploraciones | <strong>N\u00famero:<\/strong> 16.<br \/>\n<strong>Pr\u00f3logo:<\/strong> \u00c1lvaro Guzm\u00e1n Barney.<br \/>\n<strong>Autor:<\/strong> Jos\u00e9 Dar\u00edo S\u00e1enz.<br \/>\n<strong>Editorial:<\/strong> Universidad Icesi.<br \/>\n<strong>ISBN:<\/strong> 978-628-7538-93-1.<br \/>\n<strong>A\u00f1o de edici\u00f3n:<\/strong> 2022.<br \/>\n<span id=\"post-ratings-6754\" class=\"post-ratings\" data-nonce=\"062f9c60c1\"><img decoding=\"async\" id=\"rating_6754_1\" src=\"https:\/\/www.icesi.edu.co\/editorial\/wp-content\/plugins\/wp-postratings\/images\/stars_crystal\/rating_on.gif\" alt=\"1 estrella\" title=\"1 estrella\" onmouseover=\"current_rating(6754, 1, '1 estrella');\" onmouseout=\"ratings_off(5, 0, 0);\" onclick=\"rate_post();\" onkeypress=\"rate_post();\" style=\"cursor: pointer; border: 0px;\" \/><img decoding=\"async\" id=\"rating_6754_2\" src=\"https:\/\/www.icesi.edu.co\/editorial\/wp-content\/plugins\/wp-postratings\/images\/stars_crystal\/rating_on.gif\" alt=\"2 estrellas\" title=\"2 estrellas\" onmouseover=\"current_rating(6754, 2, '2 estrellas');\" onmouseout=\"ratings_off(5, 0, 0);\" onclick=\"rate_post();\" onkeypress=\"rate_post();\" style=\"cursor: pointer; border: 0px;\" \/><img decoding=\"async\" id=\"rating_6754_3\" src=\"https:\/\/www.icesi.edu.co\/editorial\/wp-content\/plugins\/wp-postratings\/images\/stars_crystal\/rating_on.gif\" alt=\"3 estrellas\" title=\"3 estrellas\" onmouseover=\"current_rating(6754, 3, '3 estrellas');\" onmouseout=\"ratings_off(5, 0, 0);\" onclick=\"rate_post();\" onkeypress=\"rate_post();\" style=\"cursor: pointer; border: 0px;\" \/><img decoding=\"async\" id=\"rating_6754_4\" src=\"https:\/\/www.icesi.edu.co\/editorial\/wp-content\/plugins\/wp-postratings\/images\/stars_crystal\/rating_on.gif\" alt=\"4 estrellas\" title=\"4 estrellas\" onmouseover=\"current_rating(6754, 4, '4 estrellas');\" onmouseout=\"ratings_off(5, 0, 0);\" onclick=\"rate_post();\" onkeypress=\"rate_post();\" style=\"cursor: pointer; border: 0px;\" \/><img decoding=\"async\" id=\"rating_6754_5\" src=\"https:\/\/www.icesi.edu.co\/editorial\/wp-content\/plugins\/wp-postratings\/images\/stars_crystal\/rating_on.gif\" alt=\"5 estrellas\" title=\"5 estrellas\" onmouseover=\"current_rating(6754, 5, '5 estrellas');\" onmouseout=\"ratings_off(5, 0, 0);\" onclick=\"rate_post();\" onkeypress=\"rate_post();\" style=\"cursor: pointer; border: 0px;\" \/> (<strong>3<\/strong> votos, promedio: <strong>5,00<\/strong> sobre 5)<br \/><span class=\"post-ratings-text\" id=\"ratings_6754_text\"><\/span><\/span><span id=\"post-ratings-6754-loading\" class=\"post-ratings-loading\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.icesi.edu.co\/editorial\/wp-content\/plugins\/wp-postratings\/images\/loading.gif\" width=\"16\" height=\"16\" class=\"post-ratings-image\" \/>Loading...<\/span>\n<table style=\"border: none;\">\n<tbody style=\"border: none;\">\n<tr valign=\"top\">\n<td valign=\"top\" style=\"border: none; vertical-align: top; height: 50%; width: 125px;\"><script type=\"text\/javascript\" src=\"\/\/cdn.plu.mx\/widget-popup.js\"><\/script><a href=\"https:\/\/plu.mx\/plum\/a\/?doi=10.18046\/EUI\/expl.16.2022\" data-popup=\"right\" data-size=\"large\" class=\"plumx-plum-print-popup\" data-site=\"plum\" data-hide-when-empty=\"true\" data-lang=\"es\" target=\"_blank\" rel=\"noopener\">\u00c9lite, orden y conflicto. Sobre c\u00f3mo se construy\u00f3 un orden social en Cali 1910-1953<\/a><br \/>\n<\/a><\/td>\n<td style=\"border: none; vertical-align: top; height: 50%; width: 125px;\"><script type=\"text\/javascript\" src=\"https:\/\/d1bxh8uas1mnw7.cloudfront.net\/assets\/embed.js\"><\/script><\/p>\n<div class=\"altmetric-embed\" data-badge-type=\"donut\" data-altmetric-id=\"151000193\"><\/div>\n<\/td>\n<td style=\"border: none; vertical-align: middle;\"><span class=\"__dimensions_badge_embed__\" data-doi=\"10.18046\/EUI\/expl.16.2022\" data-hide-zero-citations=\"true\" data-legend=\"hover-right\" data-style=\"small_circle\"><\/span><script async=\"\" src=\"https:\/\/badge.dimensions.ai\/badge.js\" charset=\"utf-8\"><\/script><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<div class=\"osc-res-tab tabbable   osc-tabs-left\"><div style=\"clear:both;width: 100%;\"><ul class=\"nav osc-res-nav nav-pills osc-tabs-left-ul\" id=\"oscitas-restabs-1-red-elite-cali-81059\"><li class=\"active\"><a href=\"#ert_pane1-0\" data-toggle=\"tab\">Descripci\u00f3n<\/a><\/li><li class=\"\"><a href=\"#ert_pane1-1\" data-toggle=\"tab\">Contenido<\/a><\/li><li class=\"\"><a href=\"#ert_pane1-2\" data-toggle=\"tab\">Autor(es)<\/a><\/li><li class=\"\"><a href=\"#ert_pane1-3\" data-toggle=\"tab\">Catalogaci\u00f3n<\/a><\/li><\/ul><\/div><div style=\"clear:both;width: 100%;\"><ul class=\"tab-content\" id=\"oscitas-restabcontent-1-red-elite-cali-81059\"><li class=\"tab-pane active\" id=\"ert_pane1-0\"><p style=\"text-align: justify;\">El libro da cuenta de la manera en que se forma una robusta red de \u00e9lite de poder conformada por personas de los sectores dominantes de Cali durante el periodo 1910-1953. Una red con tupidos v\u00ednculos pol\u00edticos, econ\u00f3micos, c\u00edvicos y culturales, en cuyo seno se hallaban alojados personas y familias con larga tradici\u00f3n de poder local y regional. Se establece el papel desempe\u00f1ado por esta red en la configuraci\u00f3n del orden social de dominaci\u00f3n en la ciudad, y c\u00f3mo logran construirlo mediante la creaci\u00f3n de patrones cognitivos y simb\u00f3licos, instituciones reguladoras, definiciones espaciales, disciplina y control policial. Estas din\u00e1micas de ordenamiento social se concretaban, para cada momento hist\u00f3rico, con decisiones fundadas en pol\u00edtica moral, procesos de estatizaci\u00f3n de conductas en el \u00e1mbito p\u00fablico, y formas de inclusi\u00f3n diferenciada con los sectores populares. Este proceso constru\u00eda ideas y s\u00edmbolos que guiaban la cotidianidad p\u00fablica, formas de regulaci\u00f3n de las conductas callejeras, clasificaciones espaciales para distribuir grupos, pr\u00e1cticas y acciones mediadas por las fuerzas coactivas para disciplinar en el marco del pensamiento oficial. Se presentan las din\u00e1micas de grupos sociales que mediante acciones colectivas contenciosas desafiaron el orden social de dominaci\u00f3n m\u00faltiple planteado por la red de \u00e9lite de poder local.<\/p>\n<p style=\"text-align: justify;\"><strong>C\u00f3mo citar (APA):<\/strong> S\u00e1enz, J.D. (2022). <i>\u00c9lite, orden y conflicto. Sobre c\u00f3mo se construy\u00f3 un orden social en Cali 1910-1953<\/i>. Cali: Editorial Universidad Icesi. DOI: <a href=\"https:\/\/doi.org\/10.18046\/EUI\/expl.16.2022\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/doi.org\/10.18046\/EUI\/expl.16.2022<\/a><\/p><\/li><li class=\"tab-pane \" id=\"ert_pane1-1\"><strong>Tabla de contenido:<\/strong><\/p>\n<p>Pr\u00f3logo<br \/>\n<i>\u00c1lvaro Guzm\u00e1n Barney<\/i><\/p>\n<p>Introducci\u00f3n<\/p>\n<p><strong>1 \/ Antecedentes y marco metodol\u00f3gico<\/strong><\/p>\n<p><strong>2 \/ Orden social dominaci\u00f3n m\u00faltiple: un enfoque anal\u00edtico<\/strong><\/p>\n<p><strong>3 \/ Los del empedrado: red de \u00e9lite de poder olig\u00e1rquica<\/strong><\/p>\n<p><strong>4 \/ Pol\u00edtica moral de las minor\u00edas: 1910-1916<\/strong><\/p>\n<p><strong>5 \/ Estatizaci\u00f3n de la vida p\u00fablica: 1926-1933<\/strong><\/p>\n<p><strong>6 \/ Inclusi\u00f3n diferenciada: 1943-1953<\/strong><\/p>\n<p><strong>7 \/ Construyendo orden social desde la red de \u00e9lite: 1910-1953<\/strong><\/p>\n<p><strong>8 \/ Desaf\u00edo al orden social de dominaci\u00f3n m\u00faltiple<\/strong><\/p>\n<p>Conclusiones<\/p>\n<p>Bibliograf\u00eda<\/p>\n<p>Sobre el autor<\/p>\n<p>\u00cdndice tem\u00e1tico<br \/><\/li><li class=\"tab-pane \" id=\"ert_pane1-2\"><ul>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/orcid.org\/0000-0002-8178-7671\" target=\"_blank\" title=\"ORCID iD\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1012\" src=\"http:\/\/www.icesi.edu.co\/editorial\/wp-content\/uploads\/2020\/06\/ORCIDiD_icon16x16.png\" style=\"margin-right: 6px;\" alt=\"Icono ORCID\" width=\"16\" height=\"16\"><\/a><b>Jos\u00e9 Dar\u00edo S\u00e1enz<\/b>, Universidad Icesi (Cali, Colombia)<\/li>\n<\/ul><\/li><li class=\"tab-pane \" id=\"ert_pane1-3\"><table>\n<tbody>\n<tr class=\"first odd\">\n<th width=\"150\">\n<p style=\"text-align: left;\">T\u00edtulo (ingl\u00e9s):<\/p>\n<\/th>\n<td class=\"data last\">Elite, order and conflict. On how a social order was built in Cali 1910-1953.<\/td>\n<\/tr>\n<tr class=\"even\">\n<th>\n<p style=\"text-align: left;\">DOI\/URL:<\/p>\n<\/th>\n<td class=\"data last\"><a href=\"https:\/\/doi.org\/10.18046\/EUI\/expl.16.2022\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/doi.org\/10.18046\/EUI\/expl.16.2022<\/a><\/td>\n<\/tr>\n<tr class=\"odd\">\n<th>\n<p style=\"text-align: left;\">Editorial(es):<\/p>\n<\/th>\n<td class=\"data last\">Universidad Icesi.<\/td>\n<\/tr>\n<tr class=\"even\">\n<th>\n<p style=\"text-align: left;\">Autor(es):<\/p>\n<\/th>\n<td class=\"data last\">Jos\u00e9 Dar\u00edo S\u00e1enz.<\/td>\n<\/tr>\n<tr class=\"odd\">\n<th>\n<p style=\"text-align: left;\">Palabras clave:<\/p>\n<\/th>\n<td class=\"data last\">\u00c9lite, Ca\u00f1a, Valle del Cauca, Colombia, Siglo XX.<\/td>\n<\/tr>\n<tr class=\"even\">\n<th>\n<p style=\"text-align: left;\">ISBN:<\/p>\n<\/th>\n<td class=\"data last\">978-628-7538-93-1.<\/td>\n<\/tr>\n<tr class=\"odd\">\n<th>\n<p style=\"text-align: left;\">Fecha de edici\u00f3n:<\/p>\n<\/th>\n<td class=\"data last\">Octubre de 2022.<\/td>\n<\/tr>\n<tr class=\"even\">\n<th>\n<p style=\"text-align: left;\">No. de p\u00e1ginas:<\/p>\n<\/th>\n<td class=\"data last\">532.<\/td>\n<\/tr>\n<tr class=\"odd\">\n<th>\n<p style=\"text-align: left;\">Idioma(s):<\/p>\n<\/th>\n<td class=\"data last\">Espa\u00f1ol.<\/td>\n<\/tr>\n<tr class=\"even\">\n<th>\n<p style=\"text-align: left;\">Formato(s):<\/p>\n<\/th>\n<td class=\"data last\">Libro electr\u00f3nico (PDF).<\/td>\n<\/tr>\n<tr class=\"odd\">\n<th>\n<p style=\"text-align: left;\">Alto x ancho:<\/p>\n<\/th>\n<td class=\"data last\">22 x 14 cm.<\/td>\n<\/tr>\n<tr class=\"even\">\n<th>\n<p style=\"text-align: left;\">Colecci\u00f3n:<\/p>\n<\/th>\n<td class=\"data last\">Exploraciones (16).<\/td>\n<\/tr>\n<tr class=\"odd\">\n<th>\n<p style=\"text-align: left;\">Producto:<\/p>\n<\/th>\n<td class=\"data last\">Libro de investigaci\u00f3n.<\/td>\n<\/tr>\n<tr class=\"last even\">\n<th>\n<p style=\"text-align: left;\">Observaciones:<\/p>\n<\/th>\n<td class=\"data last\">Incluye referencias bibliogr\u00e1ficas.<\/td>\n<\/tr>\n<tr class=\"last odd\">\n<th>\n<p style=\"text-align: left;\">Registro DSpace:<\/p>\n<\/th>\n<td class=\"data last\"><a href=\"https:\/\/doi.org\/10.18046\/EUI\/expl.16.2022\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1012\" src=\"http:\/\/www.icesi.edu.co\/editorial\/wp-content\/uploads\/2016\/04\/downloadIcon-e1460499009176.png\" alt=\"Icono de Repositorio - Contenido en la Nube\" width=\"25\" height=\"25\"><\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table><\/li><\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>T\u00edtulo completo: \u00c9lite, orden y conflicto. Sobre c\u00f3mo se construy\u00f3 un orden social en Cali 1910-1953. Colecci\u00f3n: Exploraciones | N\u00famero: 16. Pr\u00f3logo: \u00c1lvaro Guzm\u00e1n Barney. Autor: Jos\u00e9 Dar\u00edo S\u00e1enz. Editorial: Universidad Icesi. ISBN: 978-628-7538-93-1. A\u00f1o de edici\u00f3n: 2022. \u00c9lite, orden y conflicto. Sobre c\u00f3mo se construy\u00f3 un orden social en Cali 1910-1953<\/p>\n","protected":false},"author":3,"featured_media":7077,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[720,902,837,836,835,820,813,795,746,72,659,500,430,274,160,158,94],"class_list":["post-6754","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-exploraciones","tag-siglo-xx","tag-fch","tag-vida-publica","tag-red-de-elite","tag-conflicto","tag-estudios-sobre-cali","tag-orden-social","tag-795","tag-redes-sociales","tag-fdcs","tag-elite-politica","tag-historia-empresarial","tag-jose-dario-saenz","tag-libro-de-investigacion","tag-ciudad","tag-elites","tag-cali-valle-del-cauca-colombia"],"_links":{"self":[{"href":"https:\/\/www.icesi.edu.co\/editorial\/wp-json\/wp\/v2\/posts\/6754","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.icesi.edu.co\/editorial\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.icesi.edu.co\/editorial\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.icesi.edu.co\/editorial\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.icesi.edu.co\/editorial\/wp-json\/wp\/v2\/comments?post=6754"}],"version-history":[{"count":10,"href":"https:\/\/www.icesi.edu.co\/editorial\/wp-json\/wp\/v2\/posts\/6754\/revisions"}],"predecessor-version":[{"id":8426,"href":"https:\/\/www.icesi.edu.co\/editorial\/wp-json\/wp\/v2\/posts\/6754\/revisions\/8426"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.icesi.edu.co\/editorial\/wp-json\/wp\/v2\/media\/7077"}],"wp:attachment":[{"href":"https:\/\/www.icesi.edu.co\/editorial\/wp-json\/wp\/v2\/media?parent=6754"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.icesi.edu.co\/editorial\/wp-json\/wp\/v2\/categories?post=6754"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.icesi.edu.co\/editorial\/wp-json\/wp\/v2\/tags?post=6754"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}