{"id":8166,"date":"2021-12-23T12:45:00","date_gmt":"2021-12-23T17:45:00","guid":{"rendered":"https:\/\/www.icesi.edu.co\/editorial\/?p=8166"},"modified":"2025-07-30T15:07:25","modified_gmt":"2025-07-30T20:07:25","slug":"travesia-innovador","status":"publish","type":"post","link":"https:\/\/www.icesi.edu.co\/editorial\/travesia-innovador\/","title":{"rendered":"La traves\u00eda del innovador"},"content":{"rendered":"<div class=\"ead-preview\"><div class=\"ead-document\" style=\"position: relative;\"><div class=\"ead-iframe-wrapper\"><iframe src=\"\/\/docs.google.com\/viewer?url=https%3A%2F%2Frepository.icesi.edu.co%2Fbitstreams%2F6ecc4f9a-8523-43e3-8192-fa8e8a2b5085%2Fdownload&amp;embedded=true&amp;hl=en\" title=\"Embedded Document\" class=\"ead-iframe\" style=\"width: 0px;height: 0px;border: none;visibility: hidden;\"><\/iframe><\/div>\t\t\t<div class=\"ead-document-loading\" style=\"width:100%;height:100%;position:absolute;left:0;top:0;z-index:10;\">\n\t\t\t\t<div class=\"ead-loading-wrap\">\n\t\t\t\t\t<div class=\"ead-loading-main\">\n\t\t\t\t\t\t<div class=\"ead-loading\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.icesi.edu.co\/editorial\/wp-content\/plugins\/embed-any-document\/images\/loading.svg\" width=\"55\" height=\"55\" alt=\"Loader\">\n\t\t\t\t\t\t\t<span>Loading...<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"ead-loading-foot\">\n\t\t\t\t\t\t<div class=\"ead-loading-foot-title\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.icesi.edu.co\/editorial\/wp-content\/plugins\/embed-any-document\/images\/EAD-logo.svg\" alt=\"EAD Logo\" width=\"36\" height=\"23\"\/>\n\t\t\t\t\t\t\t<span>Taking too long?<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<p>\n\t\t\t\t\t\t\t<div class=\"ead-document-btn ead-reload-btn\" role=\"button\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.icesi.edu.co\/editorial\/wp-content\/plugins\/embed-any-document\/images\/reload.svg\" alt=\"Reload\" width=\"12\" height=\"12\"\/> Reload document\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<span>|<\/span>\n\t\t\t\t\t\t\t<a href=\"https:\/\/docs.google.com\/viewer?url=https%3A%2F%2Frepository.icesi.edu.co%2Fbitstreams%2F6ecc4f9a-8523-43e3-8192-fa8e8a2b5085%2Fdownload&#038;hl=en\" class=\"ead-document-btn\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.icesi.edu.co\/editorial\/wp-content\/plugins\/embed-any-document\/images\/open.svg\" alt=\"Open\" width=\"12\" height=\"12\"\/> Open in new tab\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><p class=\"embed_download\"><a href=\"https:\/\/repository.icesi.edu.co\/bitstreams\/6ecc4f9a-8523-43e3-8192-fa8e8a2b5085\/download\" download target=\"_blank\" rel=\"noopener\">Download\/Descargar <\/a><\/p><\/div>\n<strong>T\u00edtulo completo:<\/strong> La traves\u00eda del innovador.<br \/>\n<strong>Autores:<\/strong> Mar\u00eda Clara Betancourt, Francisco Camacho, Jos\u00e9 Andr\u00e9s Moncada, Andr\u00e9s Felipe Naranjo y N\u00e9stor Tobar Ara\u00fajo.<br \/>\n<strong>Editoriales:<\/strong> Universidad EAFIT, Universidad del Norte, Universidad CESA y Universidad Icesi.<br \/>\n<strong>ISBN:<\/strong> 978-628-7538-37-5.<br \/>\n<strong>A\u00f1o de edici\u00f3n:<\/strong> 2021.<br \/>\nAcceder a los <a href=\"https:\/\/www.innlab.org\/#\/resources\" target=\"_blank\" rel=\"noopener noreferrer\"><b>recursos en l\u00ednea<\/b><\/a> del libro.<br \/>\n<span id=\"post-ratings-8166\" class=\"post-ratings\" data-nonce=\"febf1c30f1\"><img decoding=\"async\" id=\"rating_8166_1\" src=\"https:\/\/www.icesi.edu.co\/editorial\/wp-content\/plugins\/wp-postratings\/images\/stars_crystal\/rating_on.gif\" alt=\"1 estrella\" title=\"1 estrella\" onmouseover=\"current_rating(8166, 1, '1 estrella');\" onmouseout=\"ratings_off(5, 0, 0);\" onclick=\"rate_post();\" onkeypress=\"rate_post();\" style=\"cursor: pointer; border: 0px;\" \/><img decoding=\"async\" id=\"rating_8166_2\" src=\"https:\/\/www.icesi.edu.co\/editorial\/wp-content\/plugins\/wp-postratings\/images\/stars_crystal\/rating_on.gif\" alt=\"2 estrellas\" title=\"2 estrellas\" onmouseover=\"current_rating(8166, 2, '2 estrellas');\" onmouseout=\"ratings_off(5, 0, 0);\" onclick=\"rate_post();\" onkeypress=\"rate_post();\" style=\"cursor: pointer; border: 0px;\" \/><img decoding=\"async\" id=\"rating_8166_3\" src=\"https:\/\/www.icesi.edu.co\/editorial\/wp-content\/plugins\/wp-postratings\/images\/stars_crystal\/rating_on.gif\" alt=\"3 estrellas\" title=\"3 estrellas\" onmouseover=\"current_rating(8166, 3, '3 estrellas');\" onmouseout=\"ratings_off(5, 0, 0);\" onclick=\"rate_post();\" onkeypress=\"rate_post();\" style=\"cursor: pointer; border: 0px;\" \/><img decoding=\"async\" id=\"rating_8166_4\" src=\"https:\/\/www.icesi.edu.co\/editorial\/wp-content\/plugins\/wp-postratings\/images\/stars_crystal\/rating_on.gif\" alt=\"4 estrellas\" title=\"4 estrellas\" onmouseover=\"current_rating(8166, 4, '4 estrellas');\" onmouseout=\"ratings_off(5, 0, 0);\" onclick=\"rate_post();\" onkeypress=\"rate_post();\" style=\"cursor: pointer; border: 0px;\" \/><img decoding=\"async\" id=\"rating_8166_5\" src=\"https:\/\/www.icesi.edu.co\/editorial\/wp-content\/plugins\/wp-postratings\/images\/stars_crystal\/rating_on.gif\" alt=\"5 estrellas\" title=\"5 estrellas\" onmouseover=\"current_rating(8166, 5, '5 estrellas');\" onmouseout=\"ratings_off(5, 0, 0);\" onclick=\"rate_post();\" onkeypress=\"rate_post();\" style=\"cursor: pointer; border: 0px;\" \/> (<strong>6<\/strong> votos, promedio: <strong>5,00<\/strong> sobre 5)<br \/><span class=\"post-ratings-text\" id=\"ratings_8166_text\"><\/span><\/span><span id=\"post-ratings-8166-loading\" class=\"post-ratings-loading\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.icesi.edu.co\/editorial\/wp-content\/plugins\/wp-postratings\/images\/loading.gif\" width=\"16\" height=\"16\" class=\"post-ratings-image\" \/>Loading...<\/span>\n<table style=\"border: none;\">\n<tbody style=\"border: none;\">\n<tr valign=\"top\">\n<td valign=\"top\" style=\"border: none; vertical-align: top; height: 50%; width: 125px;\"><script type=\"text\/javascript\" src=\"\/\/cdn.plu.mx\/widget-popup.js\"><\/script><a href=\"https:\/\/plu.mx\/plum\/a\/?doi=10.18046\/EUI\/ee.8.2021\" data-popup=\"right\" data-size=\"large\" class=\"plumx-plum-print-popup\" data-site=\"plum\" data-hide-when-empty=\"true\" data-lang=\"es\" target=\"_blank\" rel=\"noopener\">La traves\u00eda del innovador<\/a>\n<\/td>\n<td style=\"border: none; vertical-align: top; height: 50%; width: 125px;\"><script type=\"text\/javascript\" src=\"https:\/\/d1bxh8uas1mnw7.cloudfront.net\/assets\/embed.js\"><\/script><\/p>\n<div class=\"altmetric-embed\" data-badge-type=\"donut\" data-altmetric-id=\"\"><\/div>\n<\/td>\n<td style=\"border: none; vertical-align: middle;\"><span class=\"__dimensions_badge_embed__\" data-doi=\"10.18046\/EUI\/ee.8.2021\" data-hide-zero-citations=\"true\" data-legend=\"hover-right\" data-style=\"small_circle\"><\/span><script async=\"\" src=\"https:\/\/badge.dimensions.ai\/badge.js\" charset=\"utf-8\"><\/script><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<div class=\"osc-res-tab tabbable   osc-tabs-left\"><div style=\"clear:both;width: 100%;\"><ul class=\"nav osc-res-nav nav-pills osc-tabs-left-ul\" id=\"oscitas-restabs-1-travesia-innovador-24178\"><li class=\"active\"><a href=\"#ert_pane1-0\" data-toggle=\"tab\">Descripci\u00f3n<\/a><\/li><li class=\"\"><a href=\"#ert_pane1-1\" data-toggle=\"tab\">Contenido<\/a><\/li><li class=\"\"><a href=\"#ert_pane1-2\" data-toggle=\"tab\">Autores<\/a><\/li><li class=\"\"><a href=\"#ert_pane1-3\" data-toggle=\"tab\">Catalogaci\u00f3n<\/a><\/li><\/ul><\/div><div style=\"clear:both;width: 100%;\"><ul class=\"tab-content\" id=\"oscitas-restabcontent-1-travesia-innovador-24178\"><li class=\"tab-pane active\" id=\"ert_pane1-0\"><p style=\"text-align: justify;\">Este libro no es una colecci\u00f3n de teor\u00edas; es un manual que te acompa\u00f1ar\u00e1 en cada paso del proceso de innovaci\u00f3n, escrito por Jos\u00e9 Andr\u00e9s Moncada, N\u00e9stor Tobar Ara\u00fajo, Mar\u00eda Clara Betancourt, Francisco Camacho y Andr\u00e9s Felipe Naranjo, profesionales inquietos que han dedicado sus carreras a explorar los caminos m\u00e1s efectivos hacia la innovaci\u00f3n. seguir los caminos trillados; las organizaciones que realmente desean marcar la difehacer las cosas. Sin embargo, la innovaci\u00f3n no ocurre por accidente. Es un proceso que requiere direcci\u00f3n, m\u00e9todo y, sobre todo, una comprensi\u00f3n pr\u00e1ctica de las din\u00e1micas del cambio. Aqu\u00ed es donde <i>La traves\u00eda del innovador<\/i> se convierte en un aliado clave.<\/p>\n<p style=\"text-align: justify;\"><strong>C\u00f3mo citar (APA):<\/strong> Betancourt, M.C.; Camacho, F.; Moncada, J.A.; Naranjo, A.F.; Tobar Ara\u00fajo, N. (2021). <i>La traves\u00eda del innovador<\/i>. Colombia: Universidad EAFIT, Universidad del Norte, Universidad CESA y Universidad Icesi. DOI: <a href=\"https:\/\/doi.org\/10.18046\/EUI\/ee.8.2021\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/doi.org\/10.18046\/EUI\/ee.8.2021<\/a><\/p><\/li><li class=\"tab-pane \" id=\"ert_pane1-1\"><strong>Tabla de contenido:<\/strong><\/p>\n<p>Pr\u00f3logo. Los navegantes espaciales<\/p>\n<p><u>Introducci\u00f3n. As\u00ed es como todo empez\u00f3<\/u><br \/>\n<i>Bit\u00e1cora del capit\u00e1n. A\u00f1o 23 &#8211; D\u00eda 138<\/i><\/p>\n<p><strong>1 \/ Ubicar el sistema. <u>Herramientas<\/u>:<\/strong><br \/>\n<i>Matriz de problemas<\/i><br \/>\n<i>5 preguntas para iniciar<\/i><br \/>\n<i>Mapa de actores<\/i><br \/>\n<i>An\u00e1lisis de tendencias (mirada futura)<\/i><br \/>\n<i>Niveles de abstracci\u00f3n del proyecto<\/i><br \/>\n<i>Mapa de \u00e1reas de innovaci\u00f3n<\/i><br \/>\n<i>An\u00e1lisis de capacidades internas<\/i><br \/>\n<i>An\u00e1lisis de marca<\/i><br \/>\n<i>5A\u00b4s<\/i><br \/>\n<i>An\u00e1lisis del entorno<\/i><\/p>\n<p><u>Hay esperanza. Encontramos algo<\/u><br \/>\n<i>Bit\u00e1cora del capit\u00e1n. A\u00f1o 23 &#8211; D\u00eda 258<\/i><\/p>\n<p><strong>2 \/ Sentir el sistema. <u>Herramientas:<\/u><\/strong><br \/>\n<i>Entrevistas en profundidad<\/i><br \/>\n<i>Escalonamiento 5 \u201cPorqu\u00e9s\u201d<\/i><br \/>\n<i>Service Safari<\/i><br \/>\n<i>Observaci\u00f3n a la sombra (Fly on the wall)<\/i><br \/>\n<i>Seguimiento y persecuci\u00f3n detectivesca (Shadowing)<\/i><br \/>\n<i>Clasificaci\u00f3n de tarjetas y caracter\u00edsticas<\/i><\/p>\n<p><u>Misi\u00f3n exploraci\u00f3n<\/u><br \/>\n<i>Bit\u00e1cora del capit\u00e1n. A\u00f1o 24 &#8211; D\u00eda 72<\/i><\/p>\n<p><strong>3 \/ Comprender el sistema. <u>Herramientas<\/u>:<\/strong><br \/>\n<i>Mapa de experiencia<\/i><br \/>\n<i>Mapa de empat\u00eda<\/i><br \/>\n<i>Matriz de componentes de un ecosistema<\/i><br \/>\n<i>Radar de prospectiva<\/i><br \/>\n<i>Radar de la inspiraci\u00f3n<\/i><br \/>\n<i>Consumer Trend Canvas<\/i><br \/>\n<i>Mapa de oportunidad<\/i><br \/>\n<i>Brief<\/i><br \/>\n<i>Mapa del ecosistema<\/i><br \/>\n<i>Persona<\/i><br \/>\n<i>Conceptualizaci\u00f3n de oportunidades<\/i><br \/>\n<i>Enunciado de los insights<\/i><br \/>\n<i>Preguntas reto<\/i><br \/>\n<i>Top 5: Inspiraci\u00f3n para la innovaci\u00f3n<\/i><br \/>\n<i>Mapa de la oferta<\/i><br \/>\n<i>Usuarios extremos<\/i><\/p>\n<p><u>Manos a la obra. Armando el rompecabezas<\/u><br \/>\n<i>Bit\u00e1cora del capit\u00e1n. A\u00f1o 24 &#8211; D\u00eda 152<\/i><\/p>\n<p><strong>4 \/ Proponer opciones al sistema. <u>Herramientas<\/u>:<\/strong><br \/>\n<i>Mapa de experiencia<\/i><br \/>\n<i>Mapa de empat\u00eda<\/i><br \/>\n<i>Matriz de componentes de un ecosistema<\/i><br \/>\n<i>Radar de prospectiva<\/i><br \/>\n<i>Radar de la inspiraci\u00f3n<\/i><br \/>\n<i>Consumer Trend Canvas<\/i><br \/>\n<i>Mapa de oportunidad<\/i><br \/>\n<i>Brief<\/i><br \/>\n<i>Mapa del ecosistema<\/i><br \/>\n<i>Persona<\/i><br \/>\n<i>Conceptualizaci\u00f3n de oportunidades<\/i><br \/>\n<i>Enunciado de los insights<\/i><br \/>\n<i>Preguntas reto<\/i><br \/>\n<i>Top 5: Inspiraci\u00f3n para la innovaci\u00f3n<\/i><br \/>\n<i>Mapa de la oferta<\/i><br \/>\n<i>Usuarios extremos<\/i><\/p>\n<p><u>Soluciones efectivas. El Camino hacia la soluci\u00f3n<\/u><br \/>\n<i>Bit\u00e1cora del capit\u00e1n. A\u00f1o 25 &#8211; D\u00eda 59<\/i><\/p>\n<p><strong>5 \/ Ofrecer valor al sistema. <u>Herramientas<\/u>:<\/strong><br \/>\n<i>Matrices de impacto<\/i><br \/>\n<i>Propuesta de mapa del servicio (service blueprint)<\/i><br \/>\n<i>Fortalecimiento del modelo de negocio<\/i><br \/>\n<i>Hoja de ruta de la soluci\u00f3n<\/i><br \/>\n<i>Innovaci\u00f3n en comunicaci\u00f3n de marca<\/i><br \/>\n<i>Discurso de venta<\/i><br \/>\n<i>Validaci\u00f3n de mercado<\/i><br \/>\n<i>Storytelling de venta<\/i><\/p>\n<p><u>Convergencia. En la encrucijada de la innovaci\u00f3n<\/u><br \/>\n<i>Bit\u00e1cora del capit\u00e1n. A\u00f1o 26 &#8211; D\u00eda 70<\/i><\/p>\n<p><strong>6 \/ Convergenica selecci\u00f3n y filtro. <u>Herramientas<\/u>:<\/strong><br \/>\n<i>Apropiado para innovar (RNI)<\/i><br \/>\n<i>Afinidad y agrupamiento<\/i><br \/>\n<i>Votaci\u00f3n<\/i><br \/>\n<i>Priorizaci\u00f3n<\/i><br \/>\n<i>Matrices de evaluaci\u00f3n<\/i><br \/>\n<i>Ubicaci\u00f3n y diagramas de Venn<\/i><br \/>\n<i>Matriz de complementariedad<\/i><br \/>\n<i>Ara\u00f1as de valor<\/i><\/p>\n<p><u>Cierre. El final de la aventura<\/u><\/p>\n<p>Referencias<br \/><\/li><li class=\"tab-pane \" id=\"ert_pane1-2\"><ul>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/orcid.org\/0000-0002-6291-9704\" target=\"_blank\" title=\"ORCID iD\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1012\" src=\"http:\/\/www.icesi.edu.co\/editorial\/wp-content\/uploads\/2020\/06\/ORCIDiD_icon16x16.png\" style=\"margin-right: 6px;\" alt=\"Icono ORCID\" width=\"16\" height=\"16\"><\/a><b>Mar\u00eda Clara Betancourt<\/b>, Universidad Icesi (Cali, Colombia)<\/li>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/orcid.org\/0000-0003-2421-4196\" target=\"_blank\" title=\"ORCID iD\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1012\" src=\"http:\/\/www.icesi.edu.co\/editorial\/wp-content\/uploads\/2020\/06\/ORCIDiD_icon16x16.png\" style=\"margin-right: 6px;\" alt=\"Icono ORCID\" width=\"16\" height=\"16\"><\/a><b>Francisco Camacho<\/b>, Universidad Icesi (Cali, Colombia)<\/li>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/orcid.org\/0000-0002-0615-5738\" target=\"_blank\" title=\"ORCID iD\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1012\" src=\"http:\/\/www.icesi.edu.co\/editorial\/wp-content\/uploads\/2020\/06\/ORCIDiD_icon16x16.png\" style=\"margin-right: 6px;\" alt=\"Icono ORCID\" width=\"16\" height=\"16\"><\/a><b>Jos\u00e9 Andr\u00e9s Moncada<\/b>, Universidad Icesi (Cali, Colombia)<\/li>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/orcid.org\/0000-0003-0852-5322\" target=\"_blank\" title=\"ORCID iD\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1012\" src=\"http:\/\/www.icesi.edu.co\/editorial\/wp-content\/uploads\/2020\/06\/ORCIDiD_icon16x16.png\" style=\"margin-right: 6px;\" alt=\"Icono ORCID\" width=\"16\" height=\"16\"><\/a><b>Andr\u00e9s Felipe Naranjo<\/b>, Universidad Icesi (Cali, Colombia)<\/li>\n<li style=\"text-align: justify;\"><b>N\u00e9stor Tobar Ara\u00fajo<\/b>, Universidad Icesi (Cali, Colombia)<\/li>\n<\/ul><\/li><li class=\"tab-pane \" id=\"ert_pane1-3\"><table>\n<tbody>\n<tr class=\"first odd\">\n<th width=\"160\">\n<p style=\"text-align: left;\">T\u00edtulo (ingl\u00e9s):<\/p>\n<\/th>\n<td class=\"data last\">The Innovator&#8217;s Journey.<\/td>\n<\/tr>\n<tr class=\"even\">\n<th>\n<p style=\"text-align: left;\">DOI\/URL:<\/p>\n<\/th>\n<td class=\"data last\"><a href=\"https:\/\/doi.org\/10.18046\/EUI\/ee.8.2021\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/doi.org\/10.18046\/EUI\/ee.8.2021<\/a><\/td>\n<\/tr>\n<tr class=\"odd\">\n<th>\n<p style=\"text-align: left;\">Editorial(es):<\/p>\n<\/th>\n<td class=\"data last\">Universidad Icesi.<\/td>\n<\/tr>\n<tr class=\"even\">\n<th>\n<p style=\"text-align: left;\">Autoras:<\/p>\n<\/th>\n<td class=\"data last\">Mar\u00eda Clara Betancourt, Francisco Camacho, Jos\u00e9 Andr\u00e9s Moncada, Andr\u00e9s Felipe Naranjo y N\u00e9stor Tobar Ara\u00fajo.<\/td>\n<\/tr>\n<tr class=\"odd\">\n<th>\n<p style=\"text-align: left;\">Palabras clave:<\/p>\n<\/th>\n<td class=\"data last\">Innovaci\u00f3n, creatividad, dise\u00f1o.<\/td>\n<\/tr>\n<tr class=\"even\">\n<th>\n<p style=\"text-align: left;\">ISBN:<\/p>\n<\/th>\n<td class=\"data last\">978-628-7538-37-5.<\/td>\n<\/tr>\n<tr class=\"odd\">\n<th>\n<p style=\"text-align: left;\">Fecha de edici\u00f3n:<\/p>\n<\/th>\n<td class=\"data last\">Diciembre de 2021.<\/td>\n<\/tr>\n<tr class=\"even\">\n<th>\n<p style=\"text-align: left;\">No. de p\u00e1ginas:<\/p>\n<\/th>\n<td class=\"data last\">160.<\/td>\n<\/tr>\n<tr class=\"odd\">\n<th>\n<p style=\"text-align: left;\">Idioma(s):<\/p>\n<\/th>\n<td class=\"data last\">Espa\u00f1ol.<\/td>\n<\/tr>\n<tr class=\"even\">\n<th>\n<p style=\"text-align: left;\">Formato(s):<\/p>\n<\/th>\n<td class=\"data last\">Libro electr\u00f3nico (PDF).<\/td>\n<\/tr>\n<tr class=\"odd\">\n<th>\n<p style=\"text-align: left;\">Alto x ancho:<\/p>\n<\/th>\n<td class=\"data last\">23 x 18 cm.<\/td>\n<\/tr>\n<tr class=\"even\">\n<th>\n<p style=\"text-align: left;\">Colecci\u00f3n:<\/p>\n<\/th>\n<td class=\"data last\">Alianza 4U.<\/td>\n<\/tr>\n<tr class=\"odd\">\n<th>\n<p style=\"text-align: left;\">Producto:<\/p>\n<\/th>\n<td class=\"data last\">Libro de divulgaci\u00f3n.<\/td>\n<\/tr>\n<tr class=\"even\">\n<th>\n<p style=\"text-align: left;\">Observaciones:<\/p>\n<\/th>\n<td class=\"data last\">Incluye ilustraciones.<\/td>\n<\/tr>\n<tr class=\"last odd\">\n<th>\n<p style=\"text-align: left;\">Registro DSpace:<\/p>\n<\/th>\n<td class=\"data last\"><a href=\"https:\/\/hdl.handle.net\/10906\/130172\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1012\" src=\"http:\/\/www.icesi.edu.co\/editorial\/wp-content\/uploads\/2016\/04\/downloadIcon-e1460499009176.png\" alt=\"Icono de Repositorio - Contenido en la Nube\" width=\"25\" height=\"25\"><\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table><\/li><\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>T\u00edtulo completo: La traves\u00eda del innovador. Autores: Mar\u00eda Clara Betancourt, Francisco Camacho, Jos\u00e9 Andr\u00e9s Moncada, Andr\u00e9s Felipe Naranjo y N\u00e9stor Tobar Ara\u00fajo. Editoriales: Universidad EAFIT, Universidad del Norte, Universidad CESA y Universidad Icesi. ISBN: 978-628-7538-37-5. A\u00f1o de edici\u00f3n: 2021. Acceder a los recursos en l\u00ednea del libro. La traves\u00eda del innovador<\/p>\n","protected":false},"author":3,"featured_media":8174,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[802],"tags":[311,682,727,761,762,763,764,766,903,927,962,963],"class_list":["post-8166","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-academica","tag-innovacion","tag-682","tag-libro-de-divulgacion","tag-alianza-4u","tag-universidad-eafit","tag-universidad-del-norte","tag-cesa","tag-4u-academico","tag-fidca","tag-diseno-interactivo","tag-creatividad","tag-innlab"],"_links":{"self":[{"href":"https:\/\/www.icesi.edu.co\/editorial\/wp-json\/wp\/v2\/posts\/8166","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.icesi.edu.co\/editorial\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.icesi.edu.co\/editorial\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.icesi.edu.co\/editorial\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.icesi.edu.co\/editorial\/wp-json\/wp\/v2\/comments?post=8166"}],"version-history":[{"count":10,"href":"https:\/\/www.icesi.edu.co\/editorial\/wp-json\/wp\/v2\/posts\/8166\/revisions"}],"predecessor-version":[{"id":8665,"href":"https:\/\/www.icesi.edu.co\/editorial\/wp-json\/wp\/v2\/posts\/8166\/revisions\/8665"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.icesi.edu.co\/editorial\/wp-json\/wp\/v2\/media\/8174"}],"wp:attachment":[{"href":"https:\/\/www.icesi.edu.co\/editorial\/wp-json\/wp\/v2\/media?parent=8166"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.icesi.edu.co\/editorial\/wp-json\/wp\/v2\/categories?post=8166"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.icesi.edu.co\/editorial\/wp-json\/wp\/v2\/tags?post=8166"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}